{"id":19,"count":1,"description":"","link":"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/","name":"inova\u00e7\u00e3o em soldagem","slug":"inovacao-em-soldagem","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de inova\u00e7\u00e3o em soldagem - Blog Indutrom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de inova\u00e7\u00e3o em soldagem - Blog Indutrom\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Indutrom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/\",\"url\":\"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/\",\"name\":\"Arquivo de inova\u00e7\u00e3o em soldagem - Blog Indutrom\",\"isPartOf\":{\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.indutrom.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"inova\u00e7\u00e3o em soldagem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/#website\",\"url\":\"https:\/\/www.indutrom.com.br\/blog\/\",\"name\":\"Blog Indutrom\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.indutrom.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/#organization\",\"name\":\"Blog Indutrom\",\"url\":\"https:\/\/www.indutrom.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.indutrom.com.br\/blog\/wp-content\/uploads\/2025\/01\/logo-2.webp\",\"contentUrl\":\"https:\/\/www.indutrom.com.br\/blog\/wp-content\/uploads\/2025\/01\/logo-2.webp\",\"width\":849,\"height\":354,\"caption\":\"Blog Indutrom\"},\"image\":{\"@id\":\"https:\/\/www.indutrom.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de inova\u00e7\u00e3o em soldagem - Blog Indutrom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de inova\u00e7\u00e3o em soldagem - Blog Indutrom","og_url":"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/","og_site_name":"Blog Indutrom","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/","url":"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/","name":"Arquivo de inova\u00e7\u00e3o em soldagem - Blog Indutrom","isPartOf":{"@id":"https:\/\/www.indutrom.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.indutrom.com.br\/blog\/tag\/inovacao-em-soldagem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.indutrom.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"inova\u00e7\u00e3o em soldagem"}]},{"@type":"WebSite","@id":"https:\/\/www.indutrom.com.br\/blog\/#website","url":"https:\/\/www.indutrom.com.br\/blog\/","name":"Blog Indutrom","description":"","publisher":{"@id":"https:\/\/www.indutrom.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.indutrom.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.indutrom.com.br\/blog\/#organization","name":"Blog Indutrom","url":"https:\/\/www.indutrom.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.indutrom.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.indutrom.com.br\/blog\/wp-content\/uploads\/2025\/01\/logo-2.webp","contentUrl":"https:\/\/www.indutrom.com.br\/blog\/wp-content\/uploads\/2025\/01\/logo-2.webp","width":849,"height":354,"caption":"Blog Indutrom"},"image":{"@id":"https:\/\/www.indutrom.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.indutrom.com.br\/blog\/wp-json\/wp\/v2\/tags\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.indutrom.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.indutrom.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.indutrom.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}